{"id":4764,"date":"2021-09-23T16:37:40","date_gmt":"2021-09-23T13:37:40","guid":{"rendered":"https:\/\/triplex-confinium.eu\/?p=4764"},"modified":"2021-09-23T18:04:58","modified_gmt":"2021-09-23T15:04:58","slug":"tc-wall-online-3d-tool","status":"publish","type":"post","link":"https:\/\/triplex-confinium.eu\/hu\/2021\/09\/23\/tc-wall-online-3d-tool\/","title":{"rendered":"TC Wall &#8211; online 3D tool"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<blockquote>\n<div>TC wall is online 3D tool custom designed as a study case for the Lecture Digital brick: Contemporary Approaches in Working with the Brick<\/div>\n<div><\/div>\n<\/blockquote>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"eltdf-elements-holder   eltdf-one-column  eltdf-responsive-mode-768\" ><div class=\"eltdf-eh-item\"  data-item-class=\"eltdf-eh-custom-8169\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-8169\" >\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div>\n<p align=\"left\">TC wall can be used for creating different configuration of brick color patterns. TC wall enables distribution of three brick colors according to the distance to given curves.<\/p>\n<p align=\"left\">User have an opportunity to play with given parameters as well as to upload shape of the wall (rectangle in dxf format) as well as attraction curves (dxf splines) that influence distribution of colors.<\/p>\n<p align=\"left\">\n<\/div>\n<p align=\"left\">text: Bojan TEPAV\u010cEVI\u0106 &#8211; DDC-make<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-full-height vc_row-o-columns-middle vc_row-o-content-middle vc_row-flex eltdf-content-aligment-center\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"eltdf-elements-holder  eltdf-eh-full-height eltdf-one-column  eltdf-responsive-mode-768 eltdf-one-column-alignment-center\" ><div class=\"eltdf-eh-item   eltdf-horizontal-alignment-center\"  data-item-class=\"eltdf-eh-custom-6922\">\n\t<div class=\"eltdf-eh-item-inner\">\n\t\t<div class=\"eltdf-eh-item-content eltdf-eh-custom-6922\" >\n\t\t\t<div  class=\"vc_wp_text wpb_content_element\"><div class=\"widget widget_text\">\t\t\t<div class=\"textwidget\"><p><iframe loading=\"lazy\" id=\"sdv-iframe\" style=\"overflow-x: hidden; overflow-y: hidden; border-width: 0;\" src=\"https:\/\/viewer.shapediver.com\/v2\/2.20.2\/iframe\/remote.html?modelViewUrl=eu-central-1&amp;ticket=a76e5511fd31de12e99c2aae8c40ff375975f9eaf8bf823c882d3686d2fef8525b4eee0df775152448f472804ced217c0d8c8421e694ad0a83a29bf8bf4a518208f16d8ad2ac18e3b8ba35e0533eff084ffdb0f86db00c3efaa3bc88eacb8ce20ce19bf31b8fdc7ec0756ca93870ea714961de45b4f64195309992ddca219818-2c57d0e037242ad5925fb0bc47ea2134&amp; brandedMode=false&amp; showSettingsButton=false\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\">Your browser does not support iframes.<\/p>\n<\/div>\n\t\t<\/div><\/div>\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>TC Wall &#8211; online 3D tool<\/p>","protected":false},"author":4,"featured_media":4765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"categories":[97,94,99],"tags":[],"_links":{"self":[{"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/posts\/4764"}],"collection":[{"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/comments?post=4764"}],"version-history":[{"count":18,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/posts\/4764\/revisions"}],"predecessor-version":[{"id":4784,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/posts\/4764\/revisions\/4784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/media\/4765"}],"wp:attachment":[{"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/media?parent=4764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/categories?post=4764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/triplex-confinium.eu\/hu\/wp-json\/wp\/v2\/tags?post=4764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}